{"id":204417,"date":"2026-03-01T13:21:31","date_gmt":"2026-03-01T13:21:31","guid":{"rendered":"https:\/\/vitacomoda.it\/product\/west-biking-borsa-per-tubo-superiore-per-bici-tasche-laterali-in-rete-cinghie-regolabili-custodia-per-telaio-leggera-a-sgancio-rapido-accessori-per-biciclette\/"},"modified":"2026-08-24T12:12:34","modified_gmt":"2026-08-24T12:12:34","slug":"west-biking-borsa-per-tubo-superiore-per-bici-tasche-laterali-in-rete-cinghie-regolabili-custodia-per-telaio-leggera-a-sgancio-rapido-accessori-per-biciclette","status":"publish","type":"product","link":"https:\/\/vitacomoda.it\/casa\/prodotto\/west-biking-borsa-per-tubo-superiore-per-bici-tasche-laterali-in-rete-cinghie-regolabili-custodia-per-telaio-leggera-a-sgancio-rapido-accessori-per-biciclette\/","title":{"rendered":"WEST BIKING Borsa per tubo superiore per bici Tasche laterali in rete Cinghie regolabili Custodia per telaio leggera a sgancio rapido Accessori per biciclette"},"content":{"rendered":"<p style=\"text-align: center\"><video style=\"max-width: 100%\" src=\"\/\/video.aliexpress-media.com\/play\/u\/ae_sg_item\/225346697\/p\/1\/e\/6\/t\/10301\/5000409964378.mp4\" poster=\"https:\/\/ae01.alicdn.com\/kf\/Se3db26763fc54082bd254839a2ed9d0b8.jpg\" preload=\"auto\" controls=\"controls\" width=\"100%\" height=\"100%\"><\/video><\/p>\n<div>\n<div>\n<p><strong><span style=\"font-size:16px\" id=\"tl_1\">Tasche laterali in rete<\/span><\/strong><\/p>\n<p><span style=\"font-size:16px\" id=\"tl_2\">Lo spazio laterale extra consente di risparmiare spazio nella custodia principale; raggiungi facilmente piccoli oggetti come gel energetici durante la guida. <br \/><\/span><strong><span style=\"font-size:16px\" id=\"tl_3\">Cinghie regolabili a sgancio rapido<\/span><\/strong><\/p>\n<p><span style=\"font-size:16px\" id=\"tl_4\">Le cinghie a 3 punti si fissano\/rimuovono in 3 secondi; si adatta a diversi telai di bici e rimane stabile sugli urti. <br \/><\/span><strong><span style=\"font-size:16px\" id=\"tl_5\">Custodia leggera da 77 g<\/span><\/strong><\/p>\n<p><span style=\"font-size:16px\" id=\"tl_6\">Contiene telefono\/chiavi\/strumenti senza aggiungere ulteriore carico alla bicicletta; ideale per spostamenti brevi o corse in campo. <br \/><\/span><strong><span style=\"font-size:16px\" id=\"tl_7\">Tessuto antigraffio<\/span><\/strong><\/p>\n<p><span style=\"font-size:16px\" id=\"tl_8\">Il materiale resistente all&#8217;usura resiste ai segni quotidiani; rimane durevole per l&#8217;uso regolare in bicicletta. <br \/><\/span><strong><span style=\"font-size:16px\" id=\"tl_9\">Design a doppio scopo<\/span><\/strong><\/p>\n<p><span style=\"font-size:16px\" id=\"tl_10\">Si stacca come una piccola borsa per il trasporto post-ride; prendi comodamente i tuoi oggetti essenziali quando sei fuori dalla bicicletta.<\/span><\/p>\n<p><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sc1d7c58a0b8c479ea3e4f9c423e342b5f.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S39571c044053400ebb345169cb84923aJ.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S2ed6c01f5c33497a9d2866e546e859b7h.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Scf52853c59bb40bf95a9ed62a644533bv.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sd82819478ebc474b8297706a84a3aa80I.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S76236d162b1142258b19fadabd1bdf46G.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S3ea40f35ac244a928047dd613708e7c0B.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sa35a83498c6c4e8ab1cc09cb6c758a5fU.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S13c4f6af29774e4682b3a5ea1cdb8ce11.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sde5849f09d00424ebaea686df5d7fc5fO.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S740c927e44d14562988d57fa45bc2209x.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S04d4e00e9d9e4f88a6ba7e6b9c0dc7e50.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S2d15f34caef34ac7947414d0ae25aa1bo.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S21750affda8048f89f1c684499e9364fJ.jpg\" \/><\/p>\n<\/p>\n<p><span id=\"tl_11\">borsa per tubo superiore bici <br \/>custodia da bici con tasca laterale in rete <br \/>borsa per telaio bici con tracolla regolabile <br \/>custodia per bicicletta a sgancio rapido <br \/>borsa leggera per tubo superiore bici <br \/>custodia per telaio bicicletta per telefono <br \/>borsa per articoli essenziali da ciclismo per bici <br \/>borsa corta per riporre le bici da pendolare <br \/>custodia per tubo superiore bici per chiavi <br \/>borsa da bici durevole e resistente ai graffi <br \/>custodia per bici staccabile <br \/>accessori per biciclette per il ciclismo <br \/>borsa da telaio per bici di piccola capacit\u00e0 <br \/>Custodia per tubo superiore della bici aderente <br \/>custodia per bici per attrezzi <br \/>custodia multiuso per telaio bici <br \/>borsa da ciclismo per andare in giro <br \/>custodia per bici leggera da 77 g <br \/>borsa per tubo superiore bici per mountain bike <br \/>custodia regolabile per telaio della tracolla della bici<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tasche laterali in rete Lo spazio laterale extra consente di risparmiare spazio nella custodia principale; raggiungi facilmente piccoli oggetti come [&hellip;]<\/p>\n","protected":false},"featured_media":204411,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[20399,20396,19],"product_tag":[],"class_list":["post-204417","product","type-product","status-publish","has-post-thumbnail","product_cat-sport-outdoor-biciclette-monopattini","product_cat-sport-outdoor","product_cat-tutti-i-prodotti","desktop-align-left","tablet-align-left","mobile-align-center","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product\/204417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/comments?post=204417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media\/204411"}],"wp:attachment":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media?parent=204417"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_brand?post=204417"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_cat?post=204417"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_tag?post=204417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}