{"id":21045,"date":"2026-03-01T13:35:40","date_gmt":"2026-03-01T13:35:40","guid":{"rendered":"https:\/\/vitacomoda.it\/product\/luci-per-bicicletta-ricaricabili-tramite-usb-lampada-di-avvertimento-per-la-sicurezza-in-bicicletta-torcia-da-ciclismo-impermeabile-per-esterni-per-mountain-bike-e-bici-da-strada\/"},"modified":"2026-08-06T01:01:30","modified_gmt":"2026-08-06T01:01:30","slug":"luci-per-bicicletta-ricaricabili-tramite-usb-lampada-di-avvertimento-per-la-sicurezza-in-bicicletta-torcia-da-ciclismo-impermeabile-per-esterni-per-mountain-bike-e-bici-da-strada","status":"publish","type":"product","link":"https:\/\/vitacomoda.it\/casa\/prodotto\/luci-per-bicicletta-ricaricabili-tramite-usb-lampada-di-avvertimento-per-la-sicurezza-in-bicicletta-torcia-da-ciclismo-impermeabile-per-esterni-per-mountain-bike-e-bici-da-strada\/","title":{"rendered":"Luci per bicicletta ricaricabili tramite USB, lampada di avvertimento per la sicurezza in bicicletta, torcia da ciclismo impermeabile per esterni, per mountain bike e bici da strada"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<p><strong id=\"tl_1\">Design Ricaricabile<\/strong><\/p>\n<p id=\"tl_2\">Il design ricaricabile elimina la necessit\u00e0 di frequenti sostituzioni della batteria, rendendolo una scelta ecologica per i ciclisti abituali.<\/p>\n<p><strong id=\"tl_3\">Molteplici Modalit\u00e0 di Illuminazione<\/strong><\/p>\n<p id=\"tl_4\">Dotata di molteplici modalit\u00e0 di illuminazione, la luce si adatta alle varie condizioni di guida, fornendo una luminosit\u00e0 ottimale per ogni scenario.<\/p>\n<p><strong id=\"tl_5\">Tecnologia LED<\/strong><\/p>\n<p id=\"tl_6\">Dotata di tecnologia LED avanzata, questa luce per bici garantisce un&#8217;illuminazione brillante e chiara per le pedalate notturne, migliorando la visibilit\u00e0 e la sicurezza.<\/p>\n<p><strong id=\"tl_7\">Materiale del corpo in ABS resistente<\/strong><\/p>\n<p id=\"tl_8\">Realizzata in resistente materiale ABS, questa luce per bicicletta \u00e8 progettata per resistere alle sollecitazioni dell&#8217;uso quotidiano, garantendo prestazioni durature.<\/p>\n<p><strong id=\"tl_9\">Ricarica USB di tipo C<\/strong><\/p>\n<p id=\"tl_10\">La comoda ricarica USB Type-C offre un&#8217;accensione rapida ed efficiente, garantendo che la luce rimanga accesa quando ne hai pi\u00f9 bisogno.<\/p>\n<h1 id=\"tl_11\">\u200d\ufe0f\u00a0 <strong>Set di luci anteriori e posteriori per bicicletta: guida notturna sicura!<\/strong>\u00a0\u200d\ufe0f<\/h1>\n<div>\n   \u00a0\n  <\/div>\n<h4 id=\"tl_12\">Questo\u00a0 <strong>set di luci per bici<\/strong>\u00a0include un\u00a0 <strong>faro<\/strong>\u00a0e\u00a0 <strong>fanale posteriore<\/strong>, progettato per\u00a0 <strong>Ciclismo sicuro giorno e notte<\/strong>.La caratteristica del faro\u00a0 <strong>2 perline LED LH351B<\/strong>\u00a0con\u00a0 <strong>200 lumen<\/strong>\u00a0output, offerta\u00a0 <strong>3 modalit\u00e0 di illuminazione<\/strong>\u00a0(Alto\/Medio\/Basso) e un\u00a0 <strong>Modalit\u00e0 di avviso stroboscopico<\/strong>.Il fanale posteriore utilizza\u00a0 <strong>14 perline LED3014<\/strong>\u00a0con\u00a0 <strong>50 lumen<\/strong>, fornendo\u00a0 <strong>6 modalit\u00e0<\/strong>\u00a0Inclusi effetti di luce fissa e multi-strobo. <strong><br \/> Caratteristiche principali:<\/strong> <br \/> <strong>Ricarica USB di tipo C<\/strong>\u00a0&#8211; Ricarica rapida e conveniente. <br \/> <strong>Batteria per Faro da 350mAh<\/strong>\u00a0&#8211; Fino a 10 ore di autonomia (modalit\u00e0 bassa). <br \/> <strong>Batteria per fanale posteriore da 230mAh<\/strong>\u00a0&#8211; Fino a 12 ore di autonomia (modalit\u00e0 bassa). <br \/> <strong>Progettazione di Lenti Ottiche<\/strong>\u00a0&#8211; Illuminazione non abbagliante, morbida ma luminosa. <br \/> <strong>Funzione di Memoria<\/strong>\u00a0&#8211; Ricorda l&#8217;ultima modalit\u00e0 utilizzata. <br \/> <strong>Materiale impermeabile e ABS<\/strong>\u00a0&#8211; Durevole e adatto a tutte le condizioni atmosferiche. <br \/> <strong>Installazione Facile<\/strong>\u00a0&#8211; Cinturini in silicone (estensibili da 110 mm a 220 mm). <br \/> <strong>Compatto e Portatile<\/strong>\u00a0Solo 98x56x33 mm, leggero (24 g\/21 g).<\/h4>\n<div>\n   \u00a0\n  <\/div>\n<h4 id=\"tl_13\">\ufe0f\u00a0 <strong>Ideale per:<\/strong> <br \/> Commutazione urbana <br \/> Mountain bike <br \/> Ciclismo su strada <br \/> Guida notturna <br \/> Luce di sicurezza d&#8217;emergenza <br \/> <strong>Il pacchetto include:<\/strong> <br \/> 1x Faro <br \/> 1x Fanale posteriore <br \/> 1x cavo di ricarica di tipo C <br \/> (Batteria inclusa)<\/h4>\n<p style=\"font-size:16.002px;line-height:28.575px;margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px\"><strong><span id=\"tl_14\">Nota: questo \u00e8 un SET COMBO che include sia le LUCI ANTERIORI che quelle POSTERIORI. <br \/> La scelta dell&#8217;opzione singolo articolo NON include entrambe le luci.<\/span><\/strong><\/p>\n<h4 style=\"font-size:16.002px;line-height:28.575px;margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px\" id=\"tl_15\"><strong>Suggerimenti Utili:<\/strong> <br \/> Premere a lungo per 3 secondi per accendere\/spegnere. Cambia modalit\u00e0 con pressioni rapide.<\/h4>\n<p style=\"font-size:16.002px;line-height:28.575px;margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px\"><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sc4a6c121c1fe4486952ddceb2c99548dk.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S6f40a19f06f2411e83791351cca03459f.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S541190097122474290648a4afe486522f.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S3001cdf001a146b085c803cdc1d90984a.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sf24859f2de8d4dd8b971d387fc77b83as.jpg\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"\/\/ae01.alicdn.com\/kf\/Sa4e960b9525348a4acc09c47736a1182T.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Se84ea346a8d84534b529e121463843c69.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sec0b7b3eb0e2439a95b19ad7d08f241fN.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sa241d12c239e4315a0cc6dee7fcfaf24a.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S8483ac07463443e59d8843c2d6dcb4eat.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sf4947f6ea1134cdbacec01827abcc1b9H.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sb2b6298c22814165bcd9fb9071143930i.jpg\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"\/\/ae01.alicdn.com\/kf\/Se932989b7bfa4345b485a3cc6c5812cfn.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S814b81def126462fb5246b88f1ebbfaeP.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sf6313281d2fc4914b5b572ba41b43b7bd.jpg\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S2b4951a915f04ff88f5af6b582c6aa3ah.jpg\" \/><\/p>\n<div>\n<p>\n  <\/div>\n<\/p><\/div>\n<\/div>\n<p><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Design Ricaricabile Il design ricaricabile elimina la necessit\u00e0 di frequenti sostituzioni della batteria, rendendolo una scelta ecologica per i ciclisti [&hellip;]<\/p>\n","protected":false},"featured_media":21039,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":["post-21045","product","type-product","status-publish","has-post-thumbnail","product_cat-tutti-i-prodotti","desktop-align-left","tablet-align-left","mobile-align-center","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product\/21045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/comments?post=21045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media\/21039"}],"wp:attachment":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media?parent=21045"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_brand?post=21045"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_cat?post=21045"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_tag?post=21045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}