{"id":696763,"date":"2026-08-14T11:30:40","date_gmt":"2026-08-14T11:30:40","guid":{"rendered":"https:\/\/vitacomoda.it\/?post_type=product&#038;p=864101"},"modified":"2026-08-27T21:05:08","modified_gmt":"2026-08-27T21:05:08","slug":"vassoio-per-la-gestione-dei-cavi-sotto-la-scrivania-da-1-pezzo-organizer-per-fili-cavi-ciabatta-scaffale-per-ufficio-sotto-il-tavolo-u864101","status":"publish","type":"product","link":"https:\/\/vitacomoda.it\/casa\/prodotto\/vassoio-per-la-gestione-dei-cavi-sotto-la-scrivania-da-1-pezzo-organizer-per-fili-cavi-ciabatta-scaffale-per-ufficio-sotto-il-tavolo-u864101\/","title":{"rendered":"Vassoio per la gestione dei cavi sotto la scrivania da 1 pezzo, organizer per fili, cavi, ciabatta, scaffale per ufficio sotto il tavolo"},"content":{"rendered":"<p style=\"text-align: center;\"><video style=\"max-width: 100%;\" src=\"\/\/video.aliexpress-media.com\/play\/u\/ae_sg_item\/2679315043\/p\/1\/e\/6\/t\/10301\/5000237760983.mp4\" poster=\"https:\/\/ae-pic-a1.aliexpress-media.com\/kf\/S8a5933bcd3204d939d77a43e66addb73x.jpg\" preload=\"auto\" controls=\"controls\" width=\"100%\" height=\"100%\"><\/video><\/p>\n<div>\n<div>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><strong id=\"tl_1\">Caratteristiche:<\/strong><\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_2\">Materiale metallico: realizzato in metallo resistente, questo scaffale \u00e8 robusto e duraturo.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_3\">Vassoio per la gestione dei cavi: il vassoio per la gestione dei cavi aiuta a mantenere i cavi organizzati e senza grovigli.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_4\">Rastrelliera non pieghevole: questa rastrelliera non pieghevole \u00e8 perfetta per chi ha bisogno di spazio di archiviazione aggiuntivo senza compromettere la stabilit\u00e0.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_5\">Caratteristica ecologica: la caratteristica ecologica di questo rack di stoccaggio lo rende un&#8217;ottima scelta per coloro che desiderano ridurre l&#8217;impronta di carbonio.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><strong id=\"tl_6\">Specifiche:<\/strong><\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_7\">Materiale: ferro<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_8\">Peso: 554 g<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_9\">Dimensioni: 40 * 17 * 16 cm<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_10\">Colore: nero<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><strong id=\"tl_11\">L&#8217;imballaggio include:<\/strong><\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_12\">1 Rack di stoccaggio per cavi sotto la scrivania<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><strong id=\"tl_13\">Avviso:<\/strong><\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_14\">1.A causa della differenza nel display, nella luce di ripresa e nell&#8217;ambiente, ci sar\u00e0 una certa differenza di colore tra il colore reale e il colore dell&#8217;immagine, il che \u00e8 normale.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_15\">2.A causa della misurazione manuale, la dimensione del prodotto potrebbe presentare una differenza di 0,5-1 cm.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\" id=\"tl_16\">5.Se hai domande, ti preghiamo di contattarci prima e lo risolveremo per te.<\/p>\n<p style=\"font-family:\"TT Norms Pro\", \"Open Sans\", Roboto, Arial, Helvetica, sans-serif, SimSun;font-size:14px;font-weight:400;letter-spacing:normal;line-height:inherit;text-align:start;white-space:normal;color:rgb(34, 34, 34);background-color:rgb(255, 255, 255);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Scbbe28b1993145a9bd1d27f78cb4c652g.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S28bcfbf343ed406dba2e88c1ec99b2b08.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S8faaa3812aea40aa8f6b3718a4c38b03o.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sc30f50a8b42242ed9746cecb060f38c0e.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sefb1fd97c43241259dcc75b3fe933fc8G.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S6ffd1efd73884cb784c2c1b779e0c47fH.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sae09822dce3d4fc89495e81970541bbeo.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S52ffeb9af9b34ffbb6be9722cbd9c12ee.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S07408512f4c1429c8cf70d11eb848473I.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S5522e84dc81944b19895843c0c7730c3V.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S5e044c4aebfa4d938992d4316ff90ca7I.jpg\" slate-data-type=\"image\" \/><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Caratteristiche: Materiale metallico: realizzato in metallo resistente, questo scaffale \u00e8 robusto e duraturo. Vassoio per la gestione dei cavi: il [&hellip;]<\/p>\n","protected":false},"featured_media":696757,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[62258,19],"product_tag":[],"class_list":["post-696763","product","type-product","status-publish","has-post-thumbnail","product_cat-forniture-ufficio-scuola-organizer-vassoi","product_cat-tutti-i-prodotti","desktop-align-left","tablet-align-left","mobile-align-center","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product\/696763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/comments?post=696763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media\/696757"}],"wp:attachment":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media?parent=696763"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_brand?post=696763"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_cat?post=696763"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_tag?post=696763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}