{"id":711464,"date":"2026-08-14T13:07:41","date_gmt":"2026-08-14T13:07:41","guid":{"rendered":"https:\/\/vitacomoda.it\/?post_type=product&#038;p=883334"},"modified":"2026-08-28T00:38:07","modified_gmt":"2026-08-28T00:38:07","slug":"armadietto-intelligente-per-deposito-oggetti-sistema-di-stoccaggio-ad-alta-sicurezza-per-uffici-scuole-e-centri-commerciali-u883334","status":"publish","type":"product","link":"https:\/\/vitacomoda.it\/casa\/prodotto\/armadietto-intelligente-per-deposito-oggetti-sistema-di-stoccaggio-ad-alta-sicurezza-per-uffici-scuole-e-centri-commerciali-u883334\/","title":{"rendered":"Armadietto Intelligente per Deposito Oggetti, Sistema di Stoccaggio ad Alta Sicurezza per Uffici, Scuole e Centri Commerciali"},"content":{"rendered":"<p style=\"text-align: center;\"><video style=\"max-width: 100%;\" src=\"\/\/video.aliexpress-media.com\/play\/u\/ae_sg_item\/6004130652\/p\/1\/e\/6\/t\/10301\/5000537488259.mp4\" poster=\"https:\/\/ae-pic-a1.aliexpress-media.com\/kf\/S23a9743fa7ce4aaf8d4247b54f5892e5o.jpg\" preload=\"auto\" controls=\"controls\" width=\"100%\" height=\"100%\"><\/video><\/p>\n<div>\n<div>\n<div>\n<div>\n  <span style=\"font-size:14px;\"><span style=\"background-color:#f1c40f;\" id=\"tl_1\">SI PREGA DI NOTARE:<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_2\">1. Questo \u00e8 un articolo realizzato su misura. Il prezzo indicato \u00e8 puramente indicativo; il costo specifico dipender\u00e0 dalle tue esigenze e dal porto di destinazione. Contattaci per maggiori dettagli sul prodotto e per un preventivo personalizzato.<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_3\">2. Spediamo via mare!!!<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_4\">3. Consegna a domicilio: si prega di lasciare un messaggio, contattarci su WhatsApp o inviare un&#8217;email per il prezzo!!!<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_5\">4. Non esitate a contattarci via e-mail o whatsapp<\/span><\/span> <\/p>\n<p>  <span style=\"font-size:20px;\"><span style=\"background-color:#2ecc71;\" id=\"tl_6\">indirizzo email: 13598019361@163.com<\/span><\/p>\n<p> <span style=\"background-color:#2ecc71;\" id=\"tl_7\">whatsapp:+8613598019361<\/span><\/span> <\/p>\n<p>  <span style=\"font-size:16px;\"><span style=\"background-color:#3498db;\" id=\"tl_8\">Gentile acquirente,<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_9\">Questo prodotto \u00e8 realizzato su misura e il prezzo indicato non \u00e8 il prezzo finale.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_10\">Offriamo una variet\u00e0 di metodi di consegna, tra cui DDP, DAP, EXW, FCA, FAS, FOB, CFR, CIF, CPT, CIP, DAT. Il costo del trasporto deve essere calcolato in base alla modalit\u00e0 di consegna.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_11\">Possiamo personalizzare il colore, la configurazione, il modello, l&#8217;aspetto, il logo, il tipo di motore e il gruppo motopropulsore.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_12\">La cosa pi\u00f9 importante \u00e8 che devi comunicare con il nostro servizio clienti per confermare i parametri del prodotto.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_13\">I prezzi specifici variano a seconda del paese e dei requisiti personalizzati, contattare il servizio clienti.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_14\">Gli ordini non confermati dal servizio clienti non verranno spediti.<\/span><\/span> <\/p>\n<p style=\"margin:0;display: block;width: 100%;\"><img decoding=\"async\" cke-id=\"img32\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Scdecc907e29245c7b66babc5a6ca7bb5f.jpg?width=800&#038;height=494&#038;hash=1294\" style=\"width: 800px; height: 494px;\" \/><\/p>\n<p>  <span style=\"font-size:16px;\"><span style=\"background-color:#3498db;\"><\/span><\/span> <\/p>\n<style type=\"text\/css\">#detail_decorate_root .magic-0{vertical-align:top}#detail_decorate_root .magic-1{vertical-align:top;display:block;padding-right:4px;box-sizing:border-box;padding-left:4px}#detail_decorate_root .magic-2{vertical-align:top;padding-bottom:4px;box-sizing:border-box;padding-top:4px}#detail_decorate_root .magic-3{padding:0;margin:0;white-space:pre-wrap;font-size:14px}#detail_decorate_root .magic-4{text-align:center}#detail_decorate_root .magic-5{width:750px}#detail_decorate_root .magic-6{overflow:hidden;width:750px;height:178px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-7{margin-top:0;margin-left:0;width:750px;height:178px}#detail_decorate_root .magic-8{overflow:hidden;width:750px;height:754px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-9{margin-top:0;margin-left:0;width:750px;height:754px}#detail_decorate_root .magic-10{border-bottom-style:solid;border-bottom-color:#bbb;font-family:Roboto;font-size:24px;color:#000;background-color:#bbb;font-style:normal;border-bottom-width:2px;padding-top:8px;padding-bottom:4px}#detail_decorate_root .magic-11{margin-bottom:10px;line-height:0}#detail_decorate_root .magic-12{margin-bottom:0}#detail_decorate_root .magic-13{position:relative;width:100%}#detail_decorate_root .magic-14{overflow:hidden;width:750px;height:1422.1875px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-15{margin-top:0;margin-left:0;width:750px;height:1422.1875px}#detail_decorate_root .magic-16{overflow:hidden;width:750px;height:992.8125px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-17{margin-top:0;margin-left:0;width:750px;height:992.8125px}#detail_decorate_root .magic-18{overflow:hidden;width:750px;height:845px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-19{margin-top:0;margin-left:0;width:750px;height:845px}#detail_decorate_root .magic-20{overflow:hidden;width:750px;height:420.5256570713392px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-21{margin-top:0;margin-left:0;width:750.0000000000001px;height:420.5256570713392px}#detail_decorate_root .magic-22{overflow:hidden;width:750px;height:345.4838709677419px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-23{margin-top:0;margin-left:0;width:749.9999999999999px;height:345.4838709677419px}#detail_decorate_root .magic-24{overflow:hidden;width:750px;height:421.875px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-25{margin-top:0;margin-left:0;width:750px;height:421.875px}#detail_decorate_root .magic-26{overflow:hidden;width:750px;height:399.375px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-27{margin-top:0;margin-left:0;width:750px;height:399.375px}#detail_decorate_root .magic-28{overflow:hidden;width:373px;height:196.7575px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-29{margin-top:0;margin-left:0;width:373px;height:196.7575px}#detail_decorate_root .magic-30{overflow:hidden;width:373px;height:196px;margin-top:0;margin-bottom:0;margin-left:4px;margin-right:0}#detail_decorate_root .magic-31{margin-top:0;margin-left:0;width:373px;height:209.8125px}#detail_decorate_root .magic-32{overflow:hidden;width:750px;height:772.5px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-33{margin-top:0;margin-left:0;width:750px;height:772.5px}#detail_decorate_root .magic-34{overflow:hidden;width:750px;height:462.1875px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-35{margin-top:0;margin-left:0;width:750px;height:462.1875px}#detail_decorate_root .magic-36{overflow:hidden;width:750px;height:916px;margin-top:0;margin-bottom:0;margin-left:0;margin-right:0}#detail_decorate_root .magic-37{margin-top:0;margin-left:0;width:750px;height:916px}\n<\/style>\n<div  module-id=\"42064495767\" module- render=\"true\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n          \u00a0\n        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"42064495768\" module- render=\"true\">\n<div>\n<div>\n<div>\n       \u00a0\n     <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"42064495769\" module- render=\"true\">\n<div>\n<div>\n<div>\n<div>\n<div>\n        <a href=\"\" target=\"_blank\"><img decoding=\"async\" cke-id=\"img34\"  data-src=\"\/\/sc04.alicdn.com\/kf\/H93bc8c9540a3415f857596604a81f52fd\/276171880\/H93bc8c9540a3415f857596604a81f52fd.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Scf5fd402638345bfbc04c578b743f6b29.jpg?width=800&#038;height=804&#038;hash=1604\" style=\"width: 800px; height: 804px;\" \/><\/a>\n       <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"42064495770\" module- render=\"true\">\n<div  data-section=\"AliMagic-frbsue\" data-section- id=\"tl_15\">\n    Descrizione del prodotto\n   <\/div>\n<\/p><\/div>\n<div  module-id=\"42064495771\" module- render=\"true\">\n<div>\n<div>\n     <img decoding=\"async\" cke-id=\"img35\"  data-src=\"\/\/sc04.alicdn.com\/kf\/H9830517b127b4429b7d6838f393a18f7q\/276171880\/H9830517b127b4429b7d6838f393a18f7q.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S3540dcef39994f23aaed9a5560ed26b8J.jpg?width=800&#038;height=800&#038;hash=1600\" style=\"width: 800px; height: 800px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img36\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hc2350f6eec2d40b685495d3cd6faaa05p\/276171880\/Hc2350f6eec2d40b685495d3cd6faaa05p.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S01f6defdd3194652977c71092a6028e6h.jpg?width=800&#038;height=1067&#038;hash=1867\" style=\"width: 800px; height: 1067px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img37\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hddc1556409a0462b9849f767483eaefaB\/276171880\/Hddc1556409a0462b9849f767483eaefaB.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S9fab32d8def54e869f2d03365d375352Y.jpg?width=800&#038;height=1067&#038;hash=1867\" style=\"width: 800px; height: 1067px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img38\"  data-src=\"\/\/sc04.alicdn.com\/kf\/H39bb1eb81a5245c084316ac3be1d86ecK\/276171880\/H39bb1eb81a5245c084316ac3be1d86ecK.png\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S02eb001575804fce804ef96b94164007g.jpg?width=800&#038;height=426&#038;hash=1226\" style=\"width: 800px; height: 426px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img39\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hf9906e962c884fe3acd2785c17fe8ea3u\/276171880\/Hf9906e962c884fe3acd2785c17fe8ea3u.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Sb5337b3ee61944fb97321e383486bc3dQ.jpg?width=800&#038;height=452&#038;hash=1252\" style=\"width: 800px; height: 452px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img40\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hd12f501c4d174409bc0edc55e1aac4a0j\/276171880\/Hd12f501c4d174409bc0edc55e1aac4a0j.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Sa5c0c4a52eac44dc8b69a8cc85c7c1c1J.jpg?width=800&#038;height=722&#038;hash=1522\" style=\"width: 800px; height: 722px;\" \/>\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img41\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hb3376016f2dd488cbdf3ee8ebf3e3f46C\/276171880\/Hb3376016f2dd488cbdf3ee8ebf3e3f46C.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Sb5a74fba51b84735a7c2274fb564cd8ce.jpg?width=800&#038;height=722&#038;hash=1522\" style=\"width: 800px; height: 722px;\" \/>\n    <\/div>\n<div>\n      \u00a0\n    <\/div>\n<div>\n     <img decoding=\"async\" cke-id=\"img44\"  data-src=\"\/\/sc04.alicdn.com\/kf\/H0950919c19614f8c9cd406cf928a6bd6O\/276171880\/H0950919c19614f8c9cd406cf928a6bd6O.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S77fe75de86a546d2af01a355d1687b7bm.jpg?width=800&#038;height=1509&#038;hash=2309\" style=\"width: 800px; height: 1509px;\" \/>\n    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"42064495774\" module- render=\"true\">\n<div>\n<div>\n<div>\n<div>\n<div>\n        <a href=\"\" target=\"_blank\"><img decoding=\"async\" cke-id=\"img46\"  data-src=\"\/\/sc04.alicdn.com\/kf\/H4bfb381ef57b482b888bc2742778bbf6z\/276171880\/H4bfb381ef57b482b888bc2742778bbf6z.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Sb86074f995a5495eb0662023e28ba8dbQ.jpg?width=800&#038;height=1059&#038;hash=1859\" style=\"width: 800px; height: 1059px;\" \/><\/a>\n       <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"42064495775\" module- render=\"true\">\n<div>\n<div>\n<div>\n<div>\n<div>\n        <a href=\"\" target=\"_blank\"><img decoding=\"async\" cke-id=\"img47\"  data-src=\"\/\/sc04.alicdn.com\/kf\/Hccb80565c492425caf6cd3aaa2d84f13m\/276171880\/Hccb80565c492425caf6cd3aaa2d84f13m.jpg\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/Scc1f2f79c87f43b2befe8b0243fefbba3.jpg?width=800&#038;height=901&#038;hash=1701\" style=\"width: 800px; height: 901px;\" \/><\/a>\n       <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div  module-id=\"48421402786\" module- render=\"true\">\n<div  data-section=\"AliMagic-pkelgw\" data-section- id=\"tl_16\">\n    FAQ\n   <\/div>\n<\/p><\/div>\n<div  module-id=\"48421402787\" module- render=\"true\">\n<div>\n<div>\n<div>\n<div>\n<div>\n        <span id=\"tl_17\">D1: Qual \u00e8 la quantit\u00e0 minima d&#8217;ordine? <br \/> R: Una unit\u00e0 <br \/> D2: Come garantite la qualit\u00e0 del prodotto? <br \/> A: Abbiamo un team QC professionale che supervisiona e ispeziona rigorosamente ogni fase del processo, dalla produzione al confezionamento. Possiamo fornire ai clienti rapporti di ispezione professionali prima della consegna. <br \/> D3: Quali sono i termini di pagamento? <br \/> A: Termini di consegna accettati: FOB, CFR, CIF, EXW, FAS, CIP, FCA, CPT, DEQ, DDP, DDU, Express, DAF, DES; Valute accettate: USD, EUR, JPY, CAD, AUD, HKD, GBP, CNY, CHF; Metodi di pagamento accettati: T\/T, L\/C, D\/P, D\/A, MoneyGram, carta di credito, PayPal, Western Union, contanti, escrow; Lingue supportate: inglese, cinese, spagnolo, giapponese, portoghese, tedesco, arabo, francese, russo, coreano, hindi, italiano. Q4: Pu\u00f2 spiegare l&#8217;intero processo di transazione? A: 1. Negoziazione dei dettagli del prodotto e della transazione tramite email o altre app di messaggistica. 2. Firma di un contratto di vendita dopo l&#8217;accordo di entrambe le parti. <br \/> 3. Organizzare un deposito del 50% e la spedizione del campione alla nostra fabbrica. <br \/> 4. La fabbrica organizza la produzione. <br \/> 5. Testare e ispezionare le macchine prima della spedizione. <br \/> 6. Il cliente effettua un&#8217;ispezione tramite test online o in loco. <br \/> 7. Disporre il pagamento del saldo prima della spedizione. <br \/> 8. Imballare e spedire.<\/span>\n       <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> \u00a0 <\/p>\n<div  module-id=\"42064495778\" module- render=\"true\">\n   <span><\/span> <\/p>\n<div  data-section=\"AliMagic-pkelgw\" data-section- id=\"ali-anchor-AliMagic-pkelgw\">\n     \u00a0\n   <\/div>\n<p> \u00a0\n  <\/div>\n<p> \u00a0 <\/p>\n<p style=\"margin:0;display: block;width: 100%;\"><img decoding=\"async\" cke-id=\"img57\" referrerpolicy=\"no-referrer\" src=\"\/\/ae-pic-a1.aliexpress-media.com\/kf\/S8f260e3665924dff815225e23c91cd38k.jpg?width=800&#038;height=1987&#038;hash=2787\" style=\"width: 800px; height: 1987px;\" \/><br \/> \u00a0<span style=\"font-size:14px;\"><span style=\"background-color:#f1c40f;\" id=\"tl_18\">SI PREGA DI NOTARE:<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_19\">1. Questo \u00e8 un articolo realizzato su misura. Il prezzo indicato \u00e8 puramente indicativo; il costo specifico dipender\u00e0 dalle tue esigenze e dal porto di destinazione. Contattaci per maggiori dettagli sul prodotto e per un preventivo personalizzato.<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_20\">2. Spediamo via mare!!!<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_21\">3. Consegna a domicilio: si prega di lasciare un messaggio, contattarci su WhatsApp o inviare un&#8217;email per il prezzo!!!<\/span><\/p>\n<p> <span style=\"background-color:#f1c40f;\" id=\"tl_22\">4. Non esitate a contattarci via e-mail o whatsapp<\/span><\/span><\/p>\n<p> <span style=\"font-size:20px;\"><span style=\"background-color:#2ecc71;\" id=\"tl_23\">indirizzo email: 13598019361@163.com<\/span><\/p>\n<p> <span style=\"background-color:#2ecc71;\" id=\"tl_24\">whatsapp:+8613598019361<\/span><\/span><\/p>\n<p> <span style=\"font-size:16px;\"><span style=\"background-color:#3498db;\" id=\"tl_25\">Gentile acquirente,<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_26\">Questo prodotto \u00e8 realizzato su misura e il prezzo indicato non \u00e8 il prezzo finale.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_27\">Offriamo una variet\u00e0 di metodi di consegna, tra cui DDP, DAP, EXW, FCA, FAS, FOB, CFR, CIF, CPT, CIP, DAT. Il costo del trasporto deve essere calcolato in base alla modalit\u00e0 di consegna.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_28\">Possiamo personalizzare il colore, la configurazione, il modello, l&#8217;aspetto, il logo, il tipo di motore e il gruppo motopropulsore.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_29\">La cosa pi\u00f9 importante \u00e8 che devi comunicare con il nostro servizio clienti per confermare i parametri del prodotto.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_30\">I prezzi specifici variano a seconda del paese e dei requisiti personalizzati, contattare il servizio clienti.<\/span><\/p>\n<p> <span style=\"background-color:#3498db;\" id=\"tl_31\">Gli ordini non confermati dal servizio clienti non verranno spediti.<\/span><\/span><\/p>\n<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SI PREGA DI NOTARE: 1. Questo \u00e8 un articolo realizzato su misura. Il prezzo indicato \u00e8 puramente indicativo; il costo [&hellip;]<\/p>\n","protected":false},"featured_media":711458,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[62243,38595,19],"product_tag":[],"class_list":["post-711464","product","type-product","status-publish","has-post-thumbnail","product_cat-forniture-ufficio-scuola-archiviazione-raccoglitori","product_cat-industria-e-scienza-scaffalature-stoccaggio","product_cat-tutti-i-prodotti","desktop-align-left","tablet-align-left","mobile-align-center","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product\/711464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/comments?post=711464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media\/711458"}],"wp:attachment":[{"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/media?parent=711464"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_brand?post=711464"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_cat?post=711464"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vitacomoda.it\/casa\/wp-json\/wp\/v2\/product_tag?post=711464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}