{"id":352211,"date":"2026-08-11T15:00:06","date_gmt":"2026-08-11T13:00:06","guid":{"rendered":"https:\/\/vitacomoda.it\/elettronica\/prodotto\/interruttore-di-telecomando-senza-fili-rf-ad-alta-potenza-433mhz-ac85-220v-30a-1000m-per-lampada-da-soffitto-pompa-ventola-di-scarico-per-ufficio-fattoria-di-fabbrica\/"},"modified":"2026-08-11T15:00:57","modified_gmt":"2026-08-11T13:00:57","slug":"interruttore-di-telecomando-senza-fili-rf-ad-alta-potenza-433mhz-ac85-220v-30a-1000m-per-lampada-da-soffitto-pompa-ventola-di-scarico-per-ufficio-fattoria-di-fabbrica","status":"publish","type":"product","link":"https:\/\/vitacomoda.it\/elettronica\/prodotto\/interruttore-di-telecomando-senza-fili-rf-ad-alta-potenza-433mhz-ac85-220v-30a-1000m-per-lampada-da-soffitto-pompa-ventola-di-scarico-per-ufficio-fattoria-di-fabbrica\/","title":{"rendered":"Interruttore di telecomando senza fili RF ad alta potenza 433Mhz AC85-220V 30A 1000M per lampada da soffitto pompa ventola di scarico per ufficio fattoria di fabbrica"},"content":{"rendered":"<div>\n<div>\n<h2 style=\"text-align:center\" align=\"center\"><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_1\">Trasmettitore telecomandato<\/span><\/span><\/h2>\n<h2><span style=\"color:rgb(0, 0, 0);font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_2\">Batteria: batteria da 23 A 12 V (non inclusa)<\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_3\">Frequenza di trasmissione: 433 MHz<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_4\">Tipo di codifica: codice fisso<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_5\">Sensibilit\u00e0 del ricevitore: > -105 dB<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_6\">Distanza di trasmissione: 1000 M (campo aperto)<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_7\">Dimensioni: circa 55 * 28 * 10 mm<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\"><strong id=\"tl_8\">Scheda ricevitore<\/strong><\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_9\">Tensione operativa: CA 85 V &#8211; 250 V<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_10\">Tensione di uscita = Tensione operativa<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_11\">Frequenza operativa: 433 MHz (uguale al telecomando)<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_12\">Tipo di codifica: codice di apprendimento (\u00e8 possibile acquistare telecomandi extra da 315 MHz per questo ricevitore)<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_13\">Corrente di contatto nominale del rel\u00e8: 15 A\/240 V CA, 15 A\/110 V CA (notare che: sebbene il rel\u00e8 sia contrassegnato con 30 A 240 V CA.Il 30A \u00e8 per la corrente di picco del carico.La corrente nominale del carico dovrebbe essere inferiore a 15 A)<\/span><\/span><\/h2>\n<h2 style=\"font-family:arial;font-size:14px;line-height:inherit;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_14\">Dimensioni della scatola: circa 65 x 45 x 28 mm<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\"><strong id=\"tl_15\">Istruzioni:<\/strong><\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_16\">1.Jog: Il telecomando \u00e8 controllato da un pulsante.Dopo aver premuto il pulsante, il rel\u00e8 viene chiuso e quando il pulsante viene rilasciato il rel\u00e8 viene disconnesso.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_17\">2.Autobloccante: il telecomando \u00e8 controllato da un pulsante.Premere una volta il pulsante per inserire il rel\u00e8 e premerlo nuovamente per disconnettersi.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_18\">3.Interblocco: il telecomando \u00e8 controllato da due pulsanti.Premere il pulsante A per chiudere il rel\u00e8 e premere il pulsante B per disconnettersi.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_19\">4.Ritardo: dopo che l&#8217;accoppiamento \u00e8 andato a buon fine, il rel\u00e8 si disconnetter\u00e0 automaticamente dopo 5 secondi\/10 secondi\/15 secondi\/20 secondi.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\"><strong id=\"tl_20\">Impara a codificare:<\/strong><\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_21\">1.Metodo di apprendimento del Jog:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_22\">Premere una volta il pulsante di apprendimento del controller, la spia lampeggia rapidamente ed \u00e8 nello stato di apprendimento, quindi premere un pulsante qualsiasi del telecomando che si desidera imparare a inviare un codice.A questo punto, la spia lampeggia tre volte e si spegne e la corrispondenza del codice \u00e8 completata.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_23\">2.Metodo di apprendimento autobloccante:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_24\">Premere due volte il pulsante di apprendimento del controller, la spia lampeggia due volte rapidamente nello stato di apprendimento, quindi premere qualsiasi pulsante che si desidera apprendere sul telecomando per inviare un codice.A questo punto, la spia lampeggia tre volte e si spegne e la corrispondenza del codice \u00e8 completata.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_25\">3.Metodo di apprendimento ad incastro:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_26\">Premere tre volte il pulsante di apprendimento del controller, la spia lampeggia tre volte rapidamente nello stato di apprendimento, in questo momento premere il pulsante A del telecomando, la spia lampeggia tre volte, quindi premere nuovamente il pulsante B del telecomando, l&#8217;indicatore lampeggia tre volte e si spegne e la corrispondenza del codice \u00e8 completata.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_27\">4.Metodo di apprendimento con un ritardo di 5 secondi:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_28\">Premere quattro volte il pulsante di apprendimento del controller, la spia lampeggia quattro volte, quindi premere il telecomando per inviare un codice, l&#8217;indicatore del ricevitore lampeggia tre volte e quindi l&#8217;apprendimento ha esito positivo, quindi premere il telecomando per inviare il codice, il rel\u00e8 si disconnetter\u00e0 automaticamente dopo 5 secondi di chiusura.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_29\">5.Metodo di apprendimento con un ritardo di 10 secondi:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_30\">Premere cinque volte il pulsante di apprendimento del controller, la spia lampeggia cinque volte, quindi premere il telecomando per inviare il codice, l&#8217;indicatore del ricevitore lampeggia tre volte e quindi l&#8217;apprendimento ha esito positivo, quindi premere il telecomando per inviare il codice e il il rel\u00e8 si disconnetter\u00e0 automaticamente dopo 10 secondi.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_31\">6.Metodo di apprendimento con ritardo di 15 secondi:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_32\">Premere il pulsante di apprendimento del controller sei volte, la spia lampeggia sei volte, quindi premere il telecomando per inviare un codice, l&#8217;indicatore del ricevitore lampeggia tre volte e quindi l&#8217;apprendimento ha esito positivo, quindi premere il telecomando per inviare il codice e il il rel\u00e8 si disconnetter\u00e0 automaticamente dopo 15 secondi di chiusura.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_33\">7.Metodo di apprendimento con un ritardo di 20 secondi:<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><span style=\"font-size:18px;font-family:arial, helvetica, sans-serif\" id=\"tl_34\">Premere il pulsante di apprendimento del controller sette volte, la spia lampeggia sette volte, quindi premere il telecomando per inviare il codice, l&#8217;indicatore del ricevitore lampeggia tre volte e quindi l&#8217;apprendimento ha esito positivo, quindi premere il telecomando per inviare il codice e il il rel\u00e8 si spegner\u00e0 automaticamente dopo essere stato chiuso per 20 secondi.<\/span><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\"><strong id=\"tl_35\">Dati chiari:<\/strong><\/span><\/h2>\n<h2 style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><span style=\"font-size:18px\" id=\"tl_36\">Tieni premuto il pulsante di apprendimento per 8 secondi senza lasciarlo andare, la spia lampeggia una volta finch\u00e9 l&#8217;indicatore del ricevitore non lampeggia 6 volte rapidamente, la cancellazione del codice \u00e8 riuscita<\/span><\/h2>\n<div>\n <img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Seae6ad825d2449398317989f73c63b2cg.jpg\" slate-data-type=\"image\" \/>\n<\/div>\n<p style=\"font-size:14px;line-height:inherit;text-align:start;color:rgb(0, 0, 0);margin:0px;margin-bottom:0px;margin-top:0px;margin-left:0px;margin-right:0px;padding:0px;padding-bottom:0px;padding-top:0px;padding-left:0px;padding-right:0px;box-sizing:border-box\" align=\"start\"><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S870c1a94cee04ff29775e92c47c7d996D.png\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S4ec20a6af893486f8fd92897657863dew.png\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/S5bf83dd09fc544aaa0c401768a4ae7294.png\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sbd96143aae4c476ca9bd98e23d93ab6dM.jpg\" slate-data-type=\"image\" \/><img decoding=\"async\" src=\"\/\/ae01.alicdn.com\/kf\/Sb585f4f3eab7419d8a35f5cbfc63322aP.png\" slate-data-type=\"image\" \/><\/p>\n<div>\n<\/div>\n<p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trasmettitore telecomandato Batteria: batteria da 23 A 12 V (non inclusa) Frequenza di trasmissione: 433 MHz Tipo di codifica: codice [&hellip;]<\/p>\n","protected":false},"featured_media":352218,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[126],"product_tag":[],"class_list":["post-352211","product","type-product","status-publish","has-post-thumbnail","product_cat-elettronica-tech-controllo-frequenza","desktop-align-left","tablet-align-left","mobile-align-center","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/product\/352211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/comments?post=352211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/media\/352218"}],"wp:attachment":[{"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/media?parent=352211"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/product_brand?post=352211"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/product_cat?post=352211"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vitacomoda.it\/elettronica\/wp-json\/wp\/v2\/product_tag?post=352211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}